{"id":22080,"date":"2018-02-02T19:57:23","date_gmt":"2018-02-02T19:57:23","guid":{"rendered":"https:\/\/www.camac-harps.com\/blog\/?p=22080"},"modified":"2018-02-28T21:17:50","modified_gmt":"2018-02-28T21:17:50","slug":"un-harpiste-passe-la-moitie-de-sa-vie-saccorder","status":"publish","type":"post","link":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/","title":{"rendered":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&rsquo;accorder&#8230;"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8230; et l&rsquo;autre moiti\u00e9 \u00e0 jouer faux. Ce n&rsquo;est pas tout \u00e0 fait vrai (surtout si vous faites r\u00e9viser votre harpe <em>\u00e0 la perfection<\/em> par les\u00a0<a href=\"https:\/\/www.camac-harps.com\/blog\/fr\/service\/\" target=\"_blank\" rel=\"noopener\">techniciens Camac<\/a>), mais qui refuserait d&rsquo;avoir une harpe qui s&rsquo;accorde toute seule ? Nous arrivons toujours une demi-heure en avance et commen\u00e7ons \u00e0 nous inqui\u00e9ter \u00e0 ce qui va se passer \u00e0 la fin de l&rsquo;op\u00e9ra quand les intonations de l&rsquo;orchestre et de la harpe commencent \u00e0 prendre des chemins s\u00e9par\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Nicolas Lynch-Aird et Jim Woodhouse ont publi\u00e9 deux articles tr\u00e8s int\u00e9ressants sur leurs recherches concernant la fa\u00e7on de garder une harpe bien accord\u00e9e alors m\u00eame qu&rsquo;on est en train de jouer.\u00a0<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-22072\" src=\"https:\/\/www.camac-harps.com\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-200x300.png\" alt=\"strings\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-200x300.png 200w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-800x1200.png 800w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-768x1152.png 768w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-683x1024.png 683w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-300x450.png 300w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-55x83.png 55w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes-250x375.png 250w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png 936w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Les syst\u00e8mes automatiques permettant de s&rsquo;accorder ne sont pas nouveaux, comme par exemple les accordeurs \u00e9lectroniques utilis\u00e9s par la majeure partie des harpistes de nos jours. Mais en g\u00e9n\u00e9ral, il faut d&rsquo;abord jouer la corde puis comparer le son \u00e0 la note que nous voulons obtenir, pr\u00e9-programm\u00e9e dans l&rsquo;accordeur. Puis, nous ajustons la corde nous-m\u00eames ou bien il existe des syst\u00e8mes o\u00f9 un moteur le fait \u00e0 notre place.\u00a0Tout cela n&rsquo;est \u00e9videmment pas d&rsquo;une grande aide lorsque l&rsquo;on est en concert, surtout si la corde se d\u00e9saccorde avant d&rsquo;\u00eatre \u00e0 nouveau jou\u00e9e. Lynch-Aird et Woodhouse se penchent donc sur la fa\u00e7on de r\u00e9aliser des ajustements pr\u00e9ventifs pour maintenir la corde juste alors qu&rsquo;elle n&rsquo;est <em>pas <\/em>jou\u00e9e.\u00a0<\/p>\n<p style=\"text-align: justify;\">Comme tous les harpistes le savent, il y a diff\u00e9rents facteurs qui affectent la justesse d&rsquo;une corde, comme la temp\u00e9rature, l&rsquo;humidit\u00e9 ou l&rsquo;\u00e2ge de la corde. Le\u00a0<a href=\"https:\/\/www.researchgate.net\/publication\/316728946_Mechanical_Properties_of_Nylon_Harp_Strings?ev=auth_pub\">premier article<\/a>\u00a0\u00e9tudie la r\u00e9action de cordes nylon rectifi\u00e9es (recalibr\u00e9es \u00e0 un diam\u00e8tre pr\u00e9cis) et parvient \u00e0 la conclusion que le fait de maintenir une corde \u00e0 tension constante peut apporter la compensation ad\u00e9quate aux changements de temp\u00e9rature et d&rsquo;humidit\u00e9. Ils poursuivront en temps et en heure des \u00e9tudes similaires concernant les cordes boyau et carbone, mais il est d&rsquo;ores et d\u00e9j\u00e0 \u00e9vident que les cordes boyau sont bien plus impr\u00e9visibles.\u00a0Il est fort probable que le r\u00e9sultat le plus probant concernant cette \u00e9tude sur les cordes nylon est la r\u00e9action \u00e0 la tension, car une bonne connaissance de cette notion est indispensable pour mettre en oeuvre un syst\u00e8me d&rsquo;accord stable.\u00a0<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.camac-harps.com\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-22073\" src=\"https:\/\/www.camac-harps.com\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-300x200.png 300w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-768x512.png 768w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-1024x683.png 1024w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-1000x667.png 1000w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-800x533.png 800w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-55x37.png 55w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks-250x167.png 250w, https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/stringpacks.png 1675w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La meilleure mani\u00e8re de contr\u00f4ler la justesse d&rsquo;une corde, en particulier pour les cordes boyau, serait de trouver le moyen de mesurer la fr\u00e9quence de la note directement. Pour les recherches relat\u00e9es dans le\u00a0<a href=\"https:\/\/www.researchgate.net\/publication\/322516398_Frequency_Measurement_of_Musical_Instrument_Strings_Using_Piezoelectric_Transducers?ev=auth_pub\">deuxi\u00e8me article<\/a>, nous avons mis \u00e0 la disposition des chercheurs des capteurs pi\u00e9zo\u00e9lectriques (ceux que nous utilisons sur toutes nos\u00a0<a href=\"https:\/\/www.camac-harps.com\/blog\/fr\/harps-fr\/electric-fr\/\">harpes bleues<\/a>).\u00a0Lynch-Aird et Woodhouse d\u00e9crivent la fa\u00e7on dont les capteurs pi\u00e9zo peuvent \u00eatre utilis\u00e9s pour mesurer discr\u00e8tement la fr\u00e9quence d&rsquo;une note, lorsque la corde correspondante n&rsquo;est pas jou\u00e9e. Ils ont r\u00e9alis\u00e9 un mod\u00e8le afin d&rsquo;expliquer cela et ont montr\u00e9 la fa\u00e7on dont cette technique de mesure peut \u00eatre utilis\u00e9e pour garder une corde accord\u00e9e (m\u00eame une corde neuve qui a toujours tendance \u00e0 descendre).\u00a0<\/p>\n<p style=\"text-align: justify;\">Ces deux articles sont publi\u00e9s gratuitement, de fa\u00e7on \u00e0 ce qu&rsquo;ils puissent \u00eatre disponibles pour tous ceux qui sont int\u00e9ress\u00e9s sans aucun frais d&rsquo;acc\u00e8s ou de t\u00e9l\u00e9chargement.<\/p>\n<p><span style=\"font-size: 8pt;\">photos : Les Harpes Camac France<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; et l&rsquo;autre moiti\u00e9 \u00e0 jouer faux. Nicolas Lynch-Aird et Jim Woodhouse ont publi\u00e9 deux articles tr\u00e8s int\u00e9ressants sur leurs recherches concernant la fa\u00e7on de garder une harpe bien accord\u00e9e alors m\u00eame qu&rsquo;on est en train de jouer.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":22072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[533],"tags":[],"class_list":["post-22080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<title>Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&#039;accorder... - Camac Harps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&#039;accorder... - Camac Harps\" \/>\n<meta property=\"og:description\" content=\"... et l&#039;autre moiti\u00e9 \u00e0 jouer faux. Nicolas Lynch-Aird et Jim Woodhouse ont publi\u00e9 deux articles tr\u00e8s int\u00e9ressants sur leurs recherches concernant la fa\u00e7on de garder une harpe bien accord\u00e9e alors m\u00eame qu&#039;on est en train de jouer.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/\" \/>\n<meta property=\"og:site_name\" content=\"Camac Harps\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-02T19:57:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-28T21:17:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"936\" \/>\n\t<meta property=\"og:image:height\" content=\"1404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Helen Leitner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helen Leitner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/\"},\"author\":{\"name\":\"Helen Leitner\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\"},\"headline\":\"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&rsquo;accorder&#8230;\",\"datePublished\":\"2018-02-02T19:57:23+00:00\",\"dateModified\":\"2018-02-28T21:17:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/\"},\"wordCount\":599,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/01\\\/cordes.png\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/\",\"name\":\"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s'accorder... - Camac Harps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/01\\\/cordes.png\",\"datePublished\":\"2018-02-02T19:57:23+00:00\",\"dateModified\":\"2018-02-28T21:17:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/01\\\/cordes.png\",\"contentUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/01\\\/cordes.png\",\"width\":936,\"height\":1404,\"caption\":\"strings\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&rsquo;accorder&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/\",\"name\":\"Camac Harps\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\",\"name\":\"Helen Leitner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"caption\":\"Helen Leitner\"},\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/author\\\/ltnr\\\/\"}]}<\/script>","yoast_head_json":{"title":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s'accorder... - Camac Harps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/","og_locale":"fr_FR","og_type":"article","og_title":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s'accorder... - Camac Harps","og_description":"... et l'autre moiti\u00e9 \u00e0 jouer faux. Nicolas Lynch-Aird et Jim Woodhouse ont publi\u00e9 deux articles tr\u00e8s int\u00e9ressants sur leurs recherches concernant la fa\u00e7on de garder une harpe bien accord\u00e9e alors m\u00eame qu'on est en train de jouer.\u00a0","og_url":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/","og_site_name":"Camac Harps","article_published_time":"2018-02-02T19:57:23+00:00","article_modified_time":"2018-02-28T21:17:50+00:00","og_image":[{"width":936,"height":1404,"url":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png","type":"image\/png"}],"author":"Helen Leitner","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Helen Leitner","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#article","isPartOf":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/"},"author":{"name":"Helen Leitner","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22"},"headline":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&rsquo;accorder&#8230;","datePublished":"2018-02-02T19:57:23+00:00","dateModified":"2018-02-28T21:17:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/"},"wordCount":599,"commentCount":0,"image":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/","url":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/","name":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s'accorder... - Camac Harps","isPartOf":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#primaryimage"},"image":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png","datePublished":"2018-02-02T19:57:23+00:00","dateModified":"2018-02-28T21:17:50+00:00","author":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22"},"breadcrumb":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#primaryimage","url":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png","contentUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/01\/cordes.png","width":936,"height":1404,"caption":"strings"},{"@type":"BreadcrumbList","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/un-harpiste-passe-la-moitie-de-sa-vie-saccorder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camac-harps.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Un harpiste passe la moiti\u00e9 de sa vie \u00e0 s&rsquo;accorder&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#website","url":"https:\/\/www.camac-harps.com\/blog\/fr\/","name":"Camac Harps","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camac-harps.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22","name":"Helen Leitner","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","caption":"Helen Leitner"},"url":"https:\/\/www.camac-harps.com\/blog\/fr\/author\/ltnr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/22080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=22080"}],"version-history":[{"count":2,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/22080\/revisions"}],"predecessor-version":[{"id":22090,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/22080\/revisions\/22090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/media\/22072"}],"wp:attachment":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=22080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=22080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=22080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}