{"id":23335,"date":"2018-07-09T09:51:45","date_gmt":"2018-07-09T09:51:45","guid":{"rendered":"https:\/\/www.camac-harps.com\/blog\/?p=23335"},"modified":"2018-08-30T07:12:54","modified_gmt":"2018-08-30T07:12:54","slug":"harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne","status":"publish","type":"post","link":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/","title":{"rendered":"\u00ab\u00a0Harpe : les gestes de premier secours\u00a0\u00bb : vid\u00e9os disponibles en ligne !"},"content":{"rendered":"<div class=\"gdpr_opt_in\" data-cc-enable=\"vimeo\">\n<div class=\"gdpr_opt_in__inner\">Je souhaite activer le contenu vid\u00e9o et j&rsquo;accepte que des donn\u00e9es soient charg\u00e9es \u00e0 partir de Vimeo (voir <a href=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/\" target=\"_blank\">les r\u00e8gles de confidentialit\u00e9<\/a>).<\/div>\n<\/div>\n<div class=\"video_container\">\n<div class=\"video_container__inner\"><iframe title=\"Changer un levier cass\u00e9\" alt-src=\"https:\/\/player.vimeo.com\/video\/279014144?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Pas de panique ! Notre technicien en chef, Enric De Anciola, a r\u00e9alis\u00e9 quelques vid\u00e9os pour r\u00e9pondre \u00e0 certaines questions fr\u00e9quentes concernant l&rsquo;entretien d&rsquo;une harpe.\u00a0Par exemple : comment r\u00e9parer soi-m\u00eame un levier \u00e0 la maison, comme remettre les chevilles en place lorsqu&rsquo;elles tournent toutes seules et ne tiennent plus bien la corde&#8230; C&rsquo;est normal d&rsquo;avoir besoin de temps en temps de remettre les chevilles en place, quelle que soit la marque de la harpe, mais cela peut d\u00e9sar\u00e7onner tous ceux qui en sont \u00e0 leurs d\u00e9buts sur cet instrument. Nous esp\u00e9rons que les explications d&rsquo;Enric vous simplifieront la vie ! Et si vous avez des questions, vous pouvez le contacter directement <a href=\"https:\/\/www.camac-harps.com\/blog\/fr\/service\/\" target=\"_blank\" rel=\"noopener\">ici<\/a>.\u00a0<\/p>\n<div class=\"gdpr_opt_in\" data-cc-enable=\"vimeo\">\n<div class=\"gdpr_opt_in__inner\">Je souhaite activer le contenu vid\u00e9o et j&rsquo;accepte que des donn\u00e9es soient charg\u00e9es \u00e0 partir de Vimeo (voir <a href=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/\" target=\"_blank\">les r\u00e8gles de confidentialit\u00e9<\/a>).<\/div>\n<\/div>\n<div class=\"video_container\">\n<div class=\"video_container__inner\"><iframe title=\"RESERRER UNE CHEVILLE\" alt-src=\"https:\/\/player.vimeo.com\/video\/278642775?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pas de panique ! Notre technicien en chef, Enric De Anciola, a r\u00e9alis\u00e9 des vid\u00e9os montrant comment remplacer soi-m\u00eame un levier cass\u00e9 et comment remettre en place les chevilles de la harpe, ce qui peut parfois d\u00e9sar\u00e7onner ceux qui en sont \u00e0 leurs d\u00e9buts sur l&rsquo;instrument.<\/p>\n","protected":false},"author":3,"featured_media":25067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[781,533],"tags":[],"class_list":["post-23335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-actualites"],"acf":[],"yoast_head":"<title>&quot;Harpe : les gestes de premier secours&quot; : vid\u00e9os disponibles en ligne ! - Camac Harps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Harpe : les gestes de premier secours&quot; : vid\u00e9os disponibles en ligne ! - Camac Harps\" \/>\n<meta property=\"og:description\" content=\"Pas de panique ! Notre technicien en chef, Enric De Anciola, a r\u00e9alis\u00e9 des vid\u00e9os montrant comment remplacer soi-m\u00eame un levier cass\u00e9 et comment remettre en place les chevilles de la harpe, ce qui peut parfois d\u00e9sar\u00e7onner ceux qui en sont \u00e0 leurs d\u00e9buts sur l&#039;instrument.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/\" \/>\n<meta property=\"og:site_name\" content=\"Camac Harps\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-09T09:51:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-30T07:12:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helen Leitner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helen Leitner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/\"},\"author\":{\"name\":\"Helen Leitner\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\"},\"headline\":\"\u00ab\u00a0Harpe : les gestes de premier secours\u00a0\u00bb : vid\u00e9os disponibles en ligne !\",\"datePublished\":\"2018-07-09T09:51:45+00:00\",\"dateModified\":\"2018-08-30T07:12:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/\"},\"wordCount\":144,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/07\\\/harpforest.jpg\",\"articleSection\":[\"\u00c0 la une\",\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/\",\"name\":\"\\\"Harpe : les gestes de premier secours\\\" : vid\u00e9os disponibles en ligne ! - Camac Harps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/07\\\/harpforest.jpg\",\"datePublished\":\"2018-07-09T09:51:45+00:00\",\"dateModified\":\"2018-08-30T07:12:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/07\\\/harpforest.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2018\\\/07\\\/harpforest.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Photo: Jean-Marc Volta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/actualites\\\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Harpe : les gestes de premier secours\u00a0\u00bb : vid\u00e9os disponibles en ligne !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/\",\"name\":\"Camac Harps\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/59b9e6843c0338179fb914afaf144d22\",\"name\":\"Helen Leitner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g\",\"caption\":\"Helen Leitner\"},\"url\":\"https:\\\/\\\/www.camac-harps.com\\\/blog\\\/fr\\\/author\\\/ltnr\\\/\"}]}<\/script>","yoast_head_json":{"title":"\"Harpe : les gestes de premier secours\" : vid\u00e9os disponibles en ligne ! - Camac Harps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Harpe : les gestes de premier secours\" : vid\u00e9os disponibles en ligne ! - Camac Harps","og_description":"Pas de panique ! Notre technicien en chef, Enric De Anciola, a r\u00e9alis\u00e9 des vid\u00e9os montrant comment remplacer soi-m\u00eame un levier cass\u00e9 et comment remettre en place les chevilles de la harpe, ce qui peut parfois d\u00e9sar\u00e7onner ceux qui en sont \u00e0 leurs d\u00e9buts sur l'instrument.","og_url":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/","og_site_name":"Camac Harps","article_published_time":"2018-07-09T09:51:45+00:00","article_modified_time":"2018-08-30T07:12:54+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg","type":"image\/jpeg"}],"author":"Helen Leitner","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Helen Leitner","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#article","isPartOf":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/"},"author":{"name":"Helen Leitner","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22"},"headline":"\u00ab\u00a0Harpe : les gestes de premier secours\u00a0\u00bb : vid\u00e9os disponibles en ligne !","datePublished":"2018-07-09T09:51:45+00:00","dateModified":"2018-08-30T07:12:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/"},"wordCount":144,"commentCount":0,"image":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg","articleSection":["\u00c0 la une","Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/","url":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/","name":"\"Harpe : les gestes de premier secours\" : vid\u00e9os disponibles en ligne ! - Camac Harps","isPartOf":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#primaryimage"},"image":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg","datePublished":"2018-07-09T09:51:45+00:00","dateModified":"2018-08-30T07:12:54+00:00","author":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22"},"breadcrumb":{"@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#primaryimage","url":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg","contentUrl":"https:\/\/www.camac-harps.com\/blog\/wp-content\/uploads\/sites\/27\/2018\/07\/harpforest.jpg","width":1000,"height":667,"caption":"Photo: Jean-Marc Volta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/actualites\/harpe-les-gestes-de-premier-secours-videos-disponibles-en-ligne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camac-harps.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Harpe : les gestes de premier secours\u00a0\u00bb : vid\u00e9os disponibles en ligne !"}]},{"@type":"WebSite","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#website","url":"https:\/\/www.camac-harps.com\/blog\/fr\/","name":"Camac Harps","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camac-harps.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.camac-harps.com\/blog\/fr\/#\/schema\/person\/59b9e6843c0338179fb914afaf144d22","name":"Helen Leitner","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebbebff931219cff4c2d1e25c3229b2e036693f67bf237fb12f452d7a019a6da?s=96&d=mm&r=g","caption":"Helen Leitner"},"url":"https:\/\/www.camac-harps.com\/blog\/fr\/author\/ltnr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/23335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=23335"}],"version-history":[{"count":5,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/23335\/revisions"}],"predecessor-version":[{"id":25172,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/23335\/revisions\/25172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/media\/25067"}],"wp:attachment":[{"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=23335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=23335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camac-harps.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=23335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}